{"id":859,"date":"2019-10-29T21:42:07","date_gmt":"2019-10-29T21:42:07","guid":{"rendered":"https:\/\/www.ascef.com\/2020\/02\/18\/el-xxii-congreso-de-la-empresa-familiar-impulsa-la-opinion-del-empresario-con-una-encuesta-interactiva\/"},"modified":"2020-02-28T08:48:22","modified_gmt":"2020-02-28T08:48:22","slug":"el-xxii-congreso-de-la-empresa-familiar-impulsa-la-opinion-del-empresario-con-una-encuesta-interactiva","status":"publish","type":"post","link":"https:\/\/www.ascef.com\/es\/el-xxii-congreso-de-la-empresa-familiar-impulsa-la-opinion-del-empresario-con-una-encuesta-interactiva\/","title":{"rendered":"El XXII Congreso de la Empresa Familiar impulsa la opini\u00f3n del empresario con una encuesta interactiva"},"content":{"rendered":"<p>29 de Octubre de 2019\/ El XXII Congreso de la Empresa Familiar, que tuvo lugar del 27 al 29 de octubre en Murcia, impuls\u00f3 la opini\u00f3n de los asistentes con una encuesta sobre la percepci\u00f3n econ\u00f3mica ante la situaci\u00f3n pol\u00edtica y social actual.<\/p>\n<p>Los resultados indican que, para la mayor\u00eda, el 2019 registra un moderado aumento de la actividad con una limitada creaci\u00f3n neta de puestos de trabajo y se\u00f1alan que los principales retos son la gobernabilidad y las reformas estructurales. El 46% de las empresas familiares prev\u00e9n que para el 2020 se producir\u00e1 un incremento en ventas y un 35% piensa que ser\u00e1n similares a las del 2019.<br \/>\nEn cuanto a inversi\u00f3n, la empresa familiar contin\u00faa haciendo una apuesta decidida, puesto que el 73% afirma que lo aumentar\u00e1 el pr\u00f3ximo a\u00f1o.<\/p>\n<p>El Congreso cont\u00f3 con una destacada representaci\u00f3n de la ASCEF y reuni\u00f3 a destacadas personalidades del panorama econ\u00f3mico y pol\u00edtico nacional.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>29 de Octubre de 2019\/ El XXII Congreso de la Empresa Familiar, que tuvo lugar del 27 al 29 de octubre en Murcia, impuls\u00f3 la opini\u00f3n de los asistentes con una encuesta sobre la percepci\u00f3n econ\u00f3mica ante la situaci\u00f3n pol\u00edtica y social actual. Los resultados indican que, para la mayor\u00eda, el 2019 registra un moderado [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":819,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[185],"tags":[],"class_list":["post-859","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.ascef.com\/es\/wp-json\/wp\/v2\/posts\/859","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ascef.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ascef.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ascef.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ascef.com\/es\/wp-json\/wp\/v2\/comments?post=859"}],"version-history":[{"count":5,"href":"https:\/\/www.ascef.com\/es\/wp-json\/wp\/v2\/posts\/859\/revisions"}],"predecessor-version":[{"id":1137,"href":"https:\/\/www.ascef.com\/es\/wp-json\/wp\/v2\/posts\/859\/revisions\/1137"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ascef.com\/es\/wp-json\/wp\/v2\/media\/819"}],"wp:attachment":[{"href":"https:\/\/www.ascef.com\/es\/wp-json\/wp\/v2\/media?parent=859"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ascef.com\/es\/wp-json\/wp\/v2\/categories?post=859"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ascef.com\/es\/wp-json\/wp\/v2\/tags?post=859"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}