{"id":833,"date":"2020-02-18T21:01:23","date_gmt":"2020-02-18T21:01:23","guid":{"rendered":"https:\/\/www.ascef.com\/ascef\/quien-somos\/"},"modified":"2025-07-17T11:12:51","modified_gmt":"2025-07-17T11:12:51","slug":"quien-somos","status":"publish","type":"page","link":"https:\/\/www.ascef.com\/es\/quien-somos\/","title":{"rendered":"\u00bfQui\u00e9n somos?"},"content":{"rendered":"<p>La Asociaci\u00f3n Catalana de la Empresa Familiar (ASCEF) es una entidad constituida en 1998 amparada por el Instituto de la Empresa Familiar (IEF) y formada por m\u00e1s de 145 empresas representativas del tejido empresarial catal\u00e1n. Las entidades que la forman tienen un papel relevante en la econom\u00eda del pa\u00eds al estar comprometidas con la generaci\u00f3n de riqueza, la ocupaci\u00f3n laboral, el territorio y la sostenibilidad.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.ascef.com\/wp-content\/uploads\/2025\/07\/PRESENTACIO-ASCEF-2025-CASTELLANO.pdf\"><strong>Descarga la presentaci\u00f3n corporativa<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Asociaci\u00f3n Catalana de la Empresa Familiar (ASCEF) es una entidad constituida en 1998 amparada por el Instituto de la Empresa Familiar (IEF) y formada por m\u00e1s de 145 empresas representativas del tejido empresarial catal\u00e1n. Las entidades que la forman tienen un papel relevante en la econom\u00eda del pa\u00eds al estar comprometidas con la generaci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-833","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.ascef.com\/es\/wp-json\/wp\/v2\/pages\/833","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ascef.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ascef.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ascef.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ascef.com\/es\/wp-json\/wp\/v2\/comments?post=833"}],"version-history":[{"count":20,"href":"https:\/\/www.ascef.com\/es\/wp-json\/wp\/v2\/pages\/833\/revisions"}],"predecessor-version":[{"id":9891,"href":"https:\/\/www.ascef.com\/es\/wp-json\/wp\/v2\/pages\/833\/revisions\/9891"}],"wp:attachment":[{"href":"https:\/\/www.ascef.com\/es\/wp-json\/wp\/v2\/media?parent=833"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}